{"id":12780,"date":"2020-01-20T15:21:13","date_gmt":"2020-01-20T15:21:13","guid":{"rendered":"https:\/\/radiojingles24.com\/?page_id=12780"},"modified":"2020-01-20T15:21:13","modified_gmt":"2020-01-20T15:21:13","slug":"privacy","status":"publish","type":"page","link":"https:\/\/radiojingles24.com\/it\/privacy\/","title":{"rendered":"Privacy"},"content":{"rendered":"<p>Benvenuto nella nostra Privacy Policy<br \/>\n- La tua privacy \u00e8 di fondamentale importanza per noi.<br \/>\nRadio Jingles 24 Limited si trova a:<\/p>\n<p>Radio Jingles 24 Limited<br \/>\n6 Pennwell Lawn<br \/>\nWest Yorkshire, Regno Unito<br \/>\n01135346686<br \/>\n\u00c8 politica di Radio Jingles 24 Limited rispettare la tua privacy in merito a qualsiasi informazione che possiamo raccogliere durante l&#039;utilizzo del nostro sito web. La presente Informativa sulla privacy si applica a https:\/\/radiojingles24.com (di seguito, &quot;noi&quot;, &quot;noi&quot; o &quot;https:\/\/radiojingles24.com&quot;). Rispettiamo la tua privacy e ci impegniamo a proteggere le informazioni di identificazione personale che potresti fornirci attraverso il sito web. Abbiamo adottato questa informativa sulla privacy (&quot;Informativa sulla privacy&quot;) per spiegare quali informazioni possono essere raccolte sul nostro sito Web, come utilizziamo queste informazioni e in quali circostanze possiamo divulgare le informazioni a terzi. La presente Informativa sulla privacy si applica solo alle informazioni che raccogliamo attraverso il sito Web e non si applica alla nostra raccolta di informazioni da altre fonti.<br \/>\nLa presente Informativa sulla privacy, insieme ai Termini e condizioni pubblicati sul nostro sito Web, stabilisce le regole e le politiche generali che regolano l&#039;utilizzo del nostro sito Web. A seconda delle tue attivit\u00e0 quando visiti il nostro sito Web, ti potrebbe essere richiesto di accettare termini e condizioni aggiuntivi.<\/p>\n<p>- Visitatori del sito web<br \/>\nCome la maggior parte degli operatori di siti Web, Radio Jingles 24 Limited raccoglie informazioni di identificazione non personale del tipo che i browser Web e i server in genere rendono disponibili, come il tipo di browser, la preferenza della lingua, il sito di riferimento e la data e l&#039;ora di ciascuna richiesta del visitatore. Lo scopo di Radio Jingles 24 Limited nella raccolta di informazioni di identificazione non personale \u00e8 quello di comprendere meglio come i visitatori di Radio Jingles 24 Limited utilizzano il suo sito web. Di tanto in tanto, Radio Jingles 24 Limited pu\u00f2 rilasciare informazioni di identificazione non personale in forma aggregata, ad esempio, pubblicando un rapporto sulle tendenze nell&#039;utilizzo del proprio sito web.<br \/>\nRadio Jingles 24 Limited raccoglie anche informazioni potenzialmente identificative personali come gli indirizzi IP (Internet Protocol) per gli utenti registrati e per gli utenti che lasciano commenti sui post del blog https:\/\/radiojingles24.com. Radio Jingles 24 Limited divulga gli indirizzi IP degli utenti registrati e dei commentatori solo nelle stesse circostanze in cui utilizza e divulga le informazioni di identificazione personale descritte di seguito.<\/p>\n<p>- Raccolta di informazioni di identificazione personale<br \/>\nAlcuni visitatori dei siti web di Radio Jingles 24 Limited scelgono di interagire con Radio Jingles 24 Limited in modi che richiedono a Radio Jingles 24 Limited di raccogliere informazioni di identificazione personale. La quantit\u00e0 e il tipo di informazioni che Radio Jingles 24 Limited raccoglie dipende dalla natura dell&#039;interazione. Ad esempio, chiediamo ai visitatori che si iscrivono a un blog su https:\/\/radiojingles24.com di fornire un nome utente e un indirizzo e-mail.<\/p>\n<p>- Sicurezza<br \/>\nLa sicurezza delle tue informazioni personali \u00e8 importante per noi, ma ricorda che nessun metodo di trasmissione su Internet o metodo di archiviazione elettronica \u00e8 sicuro al 100%. Sebbene ci sforziamo di utilizzare mezzi commercialmente accettabili per proteggere le tue informazioni personali, non possiamo garantirne l&#039;assoluta sicurezza.<\/p>\n<p>- Annunci<br \/>\nGli annunci che appaiono sul nostro sito Web possono essere forniti agli utenti da partner pubblicitari, che possono impostare cookie. Questi cookie consentono all&#039;ad server di riconoscere il tuo computer ogni volta che ti inviano un annuncio online per compilare informazioni su di te o su altri che utilizzano il tuo computer. Queste informazioni consentono alle reti pubblicitarie, tra le altre cose, di fornire annunci pubblicitari mirati che ritengono possano interessarti maggiormente. La presente Informativa sulla privacy copre l&#039;uso dei cookie da parte di Radio Jingles 24 Limited e non copre l&#039;uso dei cookie da parte degli inserzionisti.<\/p>\n<p>- Collegamenti a siti esterni<br \/>\nIl nostro servizio pu\u00f2 contenere collegamenti a siti esterni che non sono gestiti da noi. Se fai clic su un collegamento di terze parti, verrai indirizzato al sito di quella terza parte. Ti consigliamo vivamente di rivedere l&#039;Informativa sulla privacy e i termini e le condizioni di ogni sito che visiti.<br \/>\nNon abbiamo alcun controllo e non ci assumiamo alcuna responsabilit\u00e0 per il contenuto, le politiche sulla privacy o le pratiche di siti, prodotti o servizi di terzi.<\/p>","protected":false},"excerpt":{"rendered":"<p>Benvenuto nella nostra Informativa sulla privacy: la tua privacy \u00e8 di fondamentale importanza per noi. Radio Jingles 24 Limited si trova a: Radio Jingles 24 Limited 6 ...<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-12780","page","type-page","status-publish"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Radio Jingles 24: Radio Jingles | DJ Drops | Podcast Intros | Sung Jingles<\/title>\n<meta name=\"description\" content=\"Radio Jingles, Sung Jingles, DJ Drops, and Podcast Intros for commercial, community and internet radio stations. UK Based. Prices from \u00a35. Order online.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/radiojingles24.com\/it\/privacy\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Radio Jingles 24: Radio Jingles | DJ Drops | Podcast Intros | Sung Jingles\" \/>\n<meta property=\"og:description\" content=\"Radio Jingles, Sung Jingles, DJ Drops, and Podcast Intros for commercial, community and internet radio stations. UK Based. Prices from \u00a35. Order online.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/radiojingles24.com\/it\/privacy\/\" \/>\n<meta property=\"og:site_name\" content=\"Radio Jingles 24: Radio Jingles | DJ Drops | Podcast Intros | Sung Jingles\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/radiojingles24\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@radiojingles24\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/radiojingles24.com\\\/privacy\\\/\",\"url\":\"https:\\\/\\\/radiojingles24.com\\\/privacy\\\/\",\"name\":\"Radio Jingles 24: Radio Jingles | DJ Drops | Podcast Intros | Sung Jingles\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/radiojingles24.com\\\/#website\"},\"datePublished\":\"2020-01-20T15:21:13+00:00\",\"description\":\"Radio Jingles, Sung Jingles, DJ Drops, and Podcast Intros for commercial, community and internet radio stations. UK Based. Prices from \u00a35. Order online.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/radiojingles24.com\\\/privacy\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/radiojingles24.com\\\/privacy\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/radiojingles24.com\\\/privacy\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/radiojingles24.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Privacy\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/radiojingles24.com\\\/#website\",\"url\":\"https:\\\/\\\/radiojingles24.com\\\/\",\"name\":\"Radio Jingles 24: Radio Jingles | DJ Drops | Podcast Intros | Sung Jingles\",\"description\":\"Radio Jingles, Sung Jingles, DJ Drops, and Podcast Intros for commercial, community and internet radio stations. UK Based. Prices from \u00a35. Order online.\",\"publisher\":{\"@id\":\"https:\\\/\\\/radiojingles24.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/radiojingles24.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/radiojingles24.com\\\/#organization\",\"name\":\"Radio Jingles 24\",\"url\":\"https:\\\/\\\/radiojingles24.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/radiojingles24.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/radiojingles24.com\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/RadioJingle1-1.jpg\",\"contentUrl\":\"https:\\\/\\\/radiojingles24.com\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/RadioJingle1-1.jpg\",\"width\":512,\"height\":158,\"caption\":\"Radio Jingles 24\"},\"image\":{\"@id\":\"https:\\\/\\\/radiojingles24.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/radiojingles24\\\/\",\"https:\\\/\\\/x.com\\\/radiojingles24\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Radio Jingles 24: Radio Jingles | DJ Drops | Introduzione ai podcast | Jingles cantati","description":"Jingles radiofonici, Jingles cantati, DJ Drops e Podcast Intro per stazioni radio commerciali, comunitarie e Internet. Con sede nel Regno Unito. Prezzi a partire da \u00a3 5. Ordinare on-line.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/radiojingles24.com\/it\/privacy\/","og_locale":"it_IT","og_type":"article","og_title":"Radio Jingles 24: Radio Jingles | DJ Drops | Podcast Intros | Sung Jingles","og_description":"Radio Jingles, Sung Jingles, DJ Drops, and Podcast Intros for commercial, community and internet radio stations. UK Based. Prices from \u00a35. Order online.","og_url":"https:\/\/radiojingles24.com\/it\/privacy\/","og_site_name":"Radio Jingles 24: Radio Jingles | DJ Drops | Podcast Intros | Sung Jingles","article_publisher":"https:\/\/www.facebook.com\/radiojingles24\/","twitter_card":"summary_large_image","twitter_site":"@radiojingles24","twitter_misc":{"Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/radiojingles24.com\/privacy\/","url":"https:\/\/radiojingles24.com\/privacy\/","name":"Radio Jingles 24: Radio Jingles | DJ Drops | Introduzione ai podcast | Jingles cantati","isPartOf":{"@id":"https:\/\/radiojingles24.com\/#website"},"datePublished":"2020-01-20T15:21:13+00:00","description":"Jingles radiofonici, Jingles cantati, DJ Drops e Podcast Intro per stazioni radio commerciali, comunitarie e Internet. Con sede nel Regno Unito. Prezzi a partire da \u00a3 5. Ordinare on-line.","breadcrumb":{"@id":"https:\/\/radiojingles24.com\/privacy\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/radiojingles24.com\/privacy\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/radiojingles24.com\/privacy\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/radiojingles24.com\/"},{"@type":"ListItem","position":2,"name":"Privacy"}]},{"@type":"WebSite","@id":"https:\/\/radiojingles24.com\/#website","url":"https:\/\/radiojingles24.com\/","name":"Radio Jingles 24: Radio Jingles | DJ Drops | Introduzione ai podcast | Jingles cantati","description":"Jingles radiofonici, Jingles cantati, DJ Drops e Podcast Intro per stazioni radio commerciali, comunitarie e Internet. Con sede nel Regno Unito. Prezzi a partire da \u00a3 5. Ordinare on-line.","publisher":{"@id":"https:\/\/radiojingles24.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/radiojingles24.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/radiojingles24.com\/#organization","name":"Jingle radio 24","url":"https:\/\/radiojingles24.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/radiojingles24.com\/#\/schema\/logo\/image\/","url":"https:\/\/radiojingles24.com\/wp-content\/uploads\/2019\/11\/RadioJingle1-1.jpg","contentUrl":"https:\/\/radiojingles24.com\/wp-content\/uploads\/2019\/11\/RadioJingle1-1.jpg","width":512,"height":158,"caption":"Radio Jingles 24"},"image":{"@id":"https:\/\/radiojingles24.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/radiojingles24\/","https:\/\/x.com\/radiojingles24"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/radiojingles24.com\/it\/wp-json\/wp\/v2\/pages\/12780","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiojingles24.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/radiojingles24.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/radiojingles24.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radiojingles24.com\/it\/wp-json\/wp\/v2\/comments?post=12780"}],"version-history":[{"count":1,"href":"https:\/\/radiojingles24.com\/it\/wp-json\/wp\/v2\/pages\/12780\/revisions"}],"predecessor-version":[{"id":12781,"href":"https:\/\/radiojingles24.com\/it\/wp-json\/wp\/v2\/pages\/12780\/revisions\/12781"}],"wp:attachment":[{"href":"https:\/\/radiojingles24.com\/it\/wp-json\/wp\/v2\/media?parent=12780"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}